{"id":35899,"date":"2021-04-17T08:36:50","date_gmt":"2021-04-17T06:36:50","guid":{"rendered":"http:\/\/www.fiftyandmemagazine.be\/fr\/?p=35899"},"modified":"2021-04-07T11:00:50","modified_gmt":"2021-04-07T09:00:50","slug":"pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale","status":"publish","type":"post","link":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale","title":{"rendered":"Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ?"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><h2>Pourquoi partir en d\u00e9cal\u00e9 plut\u00f4t qu\u2019en m\u00eame temps ?<\/h2>\n<p>La transition du travail vers la retraite qui dure en moyenne deux ans d\u00e9bute par une p\u00e9riode que l\u2019on appelle parfois les grandes vacances ou la lune de miel. Pendant cette p\u00e9riode, le jeune retrait\u00e9 manifeste souvent soit une suractivit\u00e9 soit une sous activit\u00e9. C\u2019est normal, mais \u00e7a ne doit pas se prolonger trop longtemps. Ensuite, pendant la p\u00e9riode de transition, il est tout \u00e0 fait\u00a0 normal que votre conjoint passe par diff\u00e9rentes \u00e9motions. Il va \u00e9prouver de la col\u00e8re, de la tristesse, de la peur. Chacun vit cette p\u00e9riode \u00e0 sa mani\u00e8re, va plus ou moins ressentir certaines de ces \u00e9motions.<br \/>\nEn traversant cette p\u00e9riode, le jeune retrait\u00e9 doit pouvoir trouver aupr\u00e8s de son conjoint de l\u2019aide et du soutien.\u00a0 Si ce dernier traverse les m\u00eames \u00ab turbulences \u00bb, c\u2019est \u00e9videmment un peu plus compliqu\u00e9 et cette \u00e9tape n\u00e9cessite alors un bonne pr\u00e9paration du couple. Vous trouverez ci-apr\u00e8s des conseils pour bien vivre cette transition en couple.<\/p>\n<h2>Comment se pr\u00e9parer quand les 2 conjoints partent \u00e0 la retraite en m\u00eame temps ?<\/h2>\n<p>Les deux membres du couple doivent en m\u00eame temps faire face \u00e0 la perte des rep\u00e8res forg\u00e9s par la vie professionnelle. Si vous n\u2019avez pas beaucoup de hobbies et que le travail occupe une position centrale dans votre couple, il est primordial d\u2019anticiper ce changement.\u00a0 A 2-3 ans de l\u2019\u00e9ch\u00e9ance, testez des <a href=\"http:\/\/www.fiftyandmemagazine.be\/fr\/evasion\/pres-de-chez-nous\/bon-plan-pour-se-distraire-a-la-pension\" target=\"_blank\" rel=\"noopener noreferrer\">activit\u00e9s<\/a> individuelles et en couple. Choisissez des activit\u00e9s que vous pourrez facilement quitter si \u00e0 la retraite vous rencontrez d\u2019autres opportunit\u00e9s. C\u2019est le moment \u00e9galement de faire le point sur les <a href=\"http:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/psycho\/comment-maintenir-un-reseau-social-a-la-retraite\" target=\"_blank\" rel=\"noopener noreferrer\">relations sociales.<\/a> En moyenne, 80% des contacts sociaux sont professionnels, en quittant le monde du travail simultan\u00e9ment, le couple doit faire face \u00e0 un effritement important de son r\u00e9seau social. Si c\u2019est possible, quittez vos emplois de mani\u00e8re progressive. C\u2019est un bon moyen de commercer \u00e0 apprivoiser progressivement la retraite et tester ensemble et seul de nouvelles activit\u00e9s. Le gouvernement travaillera en 2016 sur le principe de retraite progressive, une bonne opportunit\u00e9 pour quitter le monde du travail en douceur.<\/p>\n<h2>Quand le d\u00e9part \u00e0 la retraite du couple correspond \u00e0 la cession de leur activit\u00e9 professionnelle&#8230;<\/h2>\n<p>La port\u00e9e de la transition prend une dimension particuli\u00e8re. Le passage \u00e0 la retraite est un des moments les plus stressants pour la plupart des couples. Si \u00e0 cette \u00e9tape d\u00e9j\u00e0 stressante s\u2019ajoute la vente de l\u2019entreprise familiale, il est primordial d\u2019anticiper cette transition. Dans les faits, les c\u00e9dants sont souvent accompagn\u00e9s lors du processus de vente par des sp\u00e9cialistes financiers et des juristes, mais une fois la vente r\u00e9alis\u00e9e, ils se retrouvent\u00a0 bien seuls. L\u2019aspect \u00ab apr\u00e8s-vente \u00bb est rarement pris en compte par les accompagnants.<br \/>\nPlusieurs couples ayant v\u00e9cu ce type de transition m\u2019ont fait part de l\u2019importance d\u2019impliquer les deux conjoints dans le processus de vente. Il est tr\u00e8s fr\u00e9quent que le conjoint, qui n\u2019a pas \u00e9t\u00e9 ou n\u2019a pas souhait\u00e9 \u00eatre associ\u00e9 \u00e0 cette phase, vive difficilement la transition \u00e0 la retraite. En s\u2019impliquant dans l\u2019\u00e9valuation de l\u2019entreprise, dans les n\u00e9gociations diverses, l\u2019homme (dans la plupart des cas) entame d\u00e9j\u00e0 inconsciemment un processus de deuil, de d\u00e9tachement du monde du travail. Le conjoint plong\u00e9 dans le quotidien du travail n\u2019a pas l\u2019occasion de se projeter dans \u00ab l\u2019apr\u00e8s-vente \u00bb. Il s\u2019en suit alors une p\u00e9riode difficile \u00e0 g\u00e9rer au cours de laquelle il est primordial pour le couple de<a href=\"http:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/communication-secret-dun-couple-heureux\" target=\"_blank\" rel=\"noopener noreferrer\"> communiquer.<\/a><\/p>\n<h2>La communication au sein du couple est importante<\/h2>\n<p>Le couple face \u00e0 la retraite doit retrouver un nouvel \u00e9quilibre.\u00a0 Cette recherche d\u2019\u00e9quilibre passe in\u00e9vitablement par une communication au sein du couple. Le passage \u00e0 la retraite n\u00e9cessite une red\u00e9finition des territoires, des r\u00f4les de chacun.\u00a0 Les territoires ne concernent pas uniquement les lieux physiques comme la maison, mais aussi par exemple les agendas. Le juste \u00e9quilibre au sein d\u2019un couple, c\u2019est \u00e0 la fois garder son jardin secret et partager.\u00a0 La communication doit prendre en compte un ajustement permanent entre les go\u00fbts, les projets, les besoins de chacun et les projets \u00e0 deux.\u00a0 Cette communication doit d\u00e9buter bien avant la retraite.<\/p>\n<p>Il y a diff\u00e9rentes fa\u00e7ons pour un couple de g\u00e9rer le passage \u00e0 la retraite, il n&rsquo;y a pas de mod\u00e8le pr\u00e9\u00e9tabli. Il faut que chacun soit conscient que cela ne va pas de soi et accepte d&rsquo;y pr\u00eater attention. Le tout est de concilier les besoins et les go\u00fbts de chacun en tenant compte de ceux du couple.<\/p>\n<p><a href=\"https:\/\/www.sequoiaways.be\/fr\" target=\"_blank\" rel=\"noopener noreferrer\">sequoiaways.be<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Pourquoi partir en d\u00e9cal\u00e9 plut\u00f4t qu\u2019en m\u00eame temps ? La [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":35900,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"categories":[1105],"tags":[1147,1091],"class_list":["post-35899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-couple","tag-collab","tag-sequoia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ? - Fifty &amp; Me MAGAZINE<\/title>\n<meta name=\"description\" content=\"Le passage \u00e0 la retraite d\u2019un des conjoints impacte in\u00e9vitablement le couple. De mani\u00e8re g\u00e9n\u00e9rale, un d\u00e9part concomitant pr\u00e9sente un impact plus important et n\u00e9cessite une bonne pr\u00e9paration. Cet article vous proposera des conseils pour vivre au mieux cette transition v\u00e9cue \u00e0 deux ou en d\u00e9cal\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ? - Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"Le passage \u00e0 la retraite d\u2019un des conjoints impacte in\u00e9vitablement le couple. De mani\u00e8re g\u00e9n\u00e9rale, un d\u00e9part concomitant pr\u00e9sente un impact plus important et n\u00e9cessite une bonne pr\u00e9paration. Cet article vous proposera des conseils pour vivre au mieux cette transition v\u00e9cue \u00e0 deux ou en d\u00e9cal\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale\" \/>\n<meta property=\"og:site_name\" content=\"Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-17T06:36:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2018\/06\/couple_retraite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1110\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lauren Soukiassian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauren Soukiassian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale\",\"name\":\"Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ? - Fifty &amp; Me MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2018\/06\/couple_retraite.jpg\",\"datePublished\":\"2021-04-17T06:36:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/ebc87c29599dd51d1bb53bc5a497e45d\"},\"description\":\"Le passage \u00e0 la retraite d\u2019un des conjoints impacte in\u00e9vitablement le couple. De mani\u00e8re g\u00e9n\u00e9rale, un d\u00e9part concomitant pr\u00e9sente un impact plus important et n\u00e9cessite une bonne pr\u00e9paration. Cet article vous proposera des conseils pour vivre au mieux cette transition v\u00e9cue \u00e0 deux ou en d\u00e9cal\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#primaryimage\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2018\/06\/couple_retraite.jpg\",\"contentUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2018\/06\/couple_retraite.jpg\",\"width\":1110,\"height\":740,\"caption\":\"couple retraite\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Bien-\u00catre\",\"item\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Couple\",\"item\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/\",\"name\":\"Fifty &amp; Me MAGAZINE\",\"description\":\"Et si la vie commen\u00e7ait \u00e0 50 ans ?\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/ebc87c29599dd51d1bb53bc5a497e45d\",\"name\":\"Lauren Soukiassian\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/lauren\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ? - Fifty &amp; Me MAGAZINE","description":"Le passage \u00e0 la retraite d\u2019un des conjoints impacte in\u00e9vitablement le couple. De mani\u00e8re g\u00e9n\u00e9rale, un d\u00e9part concomitant pr\u00e9sente un impact plus important et n\u00e9cessite une bonne pr\u00e9paration. Cet article vous proposera des conseils pour vivre au mieux cette transition v\u00e9cue \u00e0 deux ou en d\u00e9cal\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale","og_locale":"fr_FR","og_type":"article","og_title":"Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ? - Fifty &amp; Me MAGAZINE","og_description":"Le passage \u00e0 la retraite d\u2019un des conjoints impacte in\u00e9vitablement le couple. De mani\u00e8re g\u00e9n\u00e9rale, un d\u00e9part concomitant pr\u00e9sente un impact plus important et n\u00e9cessite une bonne pr\u00e9paration. Cet article vous proposera des conseils pour vivre au mieux cette transition v\u00e9cue \u00e0 deux ou en d\u00e9cal\u00e9.","og_url":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale","og_site_name":"Fifty &amp; Me MAGAZINE","article_published_time":"2021-04-17T06:36:50+00:00","og_image":[{"width":1110,"height":740,"url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2018\/06\/couple_retraite.jpg","type":"image\/jpeg"}],"author":"Lauren Soukiassian","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lauren Soukiassian","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale","name":"Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ? - Fifty &amp; Me MAGAZINE","isPartOf":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#primaryimage"},"image":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#primaryimage"},"thumbnailUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2018\/06\/couple_retraite.jpg","datePublished":"2021-04-17T06:36:50+00:00","author":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/ebc87c29599dd51d1bb53bc5a497e45d"},"description":"Le passage \u00e0 la retraite d\u2019un des conjoints impacte in\u00e9vitablement le couple. De mani\u00e8re g\u00e9n\u00e9rale, un d\u00e9part concomitant pr\u00e9sente un impact plus important et n\u00e9cessite une bonne pr\u00e9paration. Cet article vous proposera des conseils pour vivre au mieux cette transition v\u00e9cue \u00e0 deux ou en d\u00e9cal\u00e9.","breadcrumb":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#primaryimage","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2018\/06\/couple_retraite.jpg","contentUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2018\/06\/couple_retraite.jpg","width":1110,"height":740,"caption":"couple retraite"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple\/pas-toucher-couple-partir-a-la-retraite-en-meme-temps-ou-en-decale#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Bien-\u00catre","item":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre"},{"@type":"ListItem","position":2,"name":"Couple","item":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/couple"},{"@type":"ListItem","position":3,"name":"Couple : est-ce pr\u00e9f\u00e9rable de partir \u00e0 la retraite en m\u00eame temps ou en d\u00e9cal\u00e9 ?"}]},{"@type":"WebSite","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/","name":"Fifty &amp; Me MAGAZINE","description":"Et si la vie commen\u00e7ait \u00e0 50 ans ?","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/ebc87c29599dd51d1bb53bc5a497e45d","name":"Lauren Soukiassian","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/lauren"}]}},"modified_by":"Magali Duqu\u00e9","_links":{"self":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/35899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/comments?post=35899"}],"version-history":[{"count":6,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/35899\/revisions"}],"predecessor-version":[{"id":41655,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/35899\/revisions\/41655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media\/35900"}],"wp:attachment":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media?parent=35899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/categories?post=35899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/tags?post=35899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}