{"id":4168,"date":"2015-08-21T16:00:28","date_gmt":"2015-08-21T14:00:28","guid":{"rendered":"http:\/\/www.life-magazine.be\/fr\/?p=4168"},"modified":"2018-03-12T12:11:09","modified_gmt":"2018-03-12T11:11:09","slug":"christophe-van-de-weghe-sa-success-story","status":"publish","type":"post","link":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story","title":{"rendered":"Christophe Van de Weghe, sa success-story"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p style=\"text-align: justify;\"><strong><span style=\"color: #ff6600;\">A<\/span> 47 ans, le Belge Christophe Van de Weghe fait valoir un parcours atypique dont le fil rouge est incontestablement le go\u00fbt du beau doubl\u00e9 de celui de l\u2019excellence. Le sportif de haut niveau qu\u2019il \u00e9tait a fait place \u00e0 un galeriste en vue qui \u00e9volue dans les plus hautes sph\u00e8res du march\u00e9 secondaire. Form\u00e9 par Larry Gagosian, \u00e0 qui il reconna\u00eet devoir beaucoup, il s\u2019est \u00e9tabli non loin de son mentor \u00e0 la faveur d\u2019une galerie situ\u00e9e sur la prestigieuse Madison Avenue, \u00e0 New York.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1344 size-full\" src=\"http:\/\/www.gentleman.be\/fr\/wp-content\/uploads\/2015\/01\/Web-Ch-Van-De-Weghe-1.jpg\" alt=\"Web Ch Van De Weghe 1\" width=\"600\" height=\"520\" \/><\/p>\n<p style=\"text-align: justify;\">\u00ab If I can make it there, I\u2019ll make it anywhere\u00a0\u00bb, impossible de ne pas songer \u00e0 la chanson de Sinatra quand on \u00e9coute le fabuleux parcours de Christophe Van de Weghe, galeriste \u00e9tabli au sommet du march\u00e9 de l\u2019art. L\u2019homme s\u2019est hiss\u00e9 \u00e0 la force des poignets, il a toujours pu compter sur eux, gravissant petit \u00e0 petit les \u00e9chelons d\u2019une carri\u00e8re qu\u2019il a commenc\u00e9e le plus modestement du monde. Son parcours a tout d\u2019une success-story \u00e0 l\u2019am\u00e9ricaine. D\u2019ailleurs, l\u2019homme a h\u00e9rit\u00e9 de son pays d\u2019adoption cette l\u00e9gendaire d\u00e9contraction qui fluidifie les contacts sociaux. Quand il vous appelle par votre pr\u00e9nom, c\u2019est comme si vous le connaissiez depuis toujours.<\/p>\n<p style=\"text-align: justify;\">Loquace, il revient volontiers sur le chemin qui a \u00e9t\u00e9 le sien avant qu\u2019il ne tr\u00f4ne au firmament des marchands d\u2019art. \u00ab\u00a0J\u2019ai grandi \u00e0 Knokke, explique-t-il. Je faisais partie des espoirs du tennis. J\u2019ai gagn\u00e9 mon premier tournoi \u00e0 11 ans. A 13 ans, on m\u2019a envoy\u00e9 en Floride pour suivre des cours \u00e0 la Hopman Tennis Academy qui \u00e0 cette \u00e9poque \u00e9tait le meilleur endroit pour pr\u00e9parer une carri\u00e8re professionnelle. Le matin, j\u2019allais au cours dans une public high school. Ce jusque 14h30, avant de consacrer le reste de ma journ\u00e9e au tennis. Je me suis lanc\u00e9 sur le circuit ATP, les choses allaient plut\u00f4t bien pour moi. Malheureusement, \u00e0 19 ans, je me suis bless\u00e9 au dos. Une double hernie discale. Le m\u00e9decin s\u2019est montr\u00e9 sans appel\u00a0: impossible de continuer le tennis \u00e0 ce niveau.\u00a0\u00bb Pour Van\u00a0de\u00a0Weghe, la nouvelle tombe comme un couperet. \u00ab\u00a0J\u2019ai continu\u00e9 \u00e0 jouer un peu pendant deux ans, juste pour d\u00e9crocher une bourse \u00e0 la Pepperdine University, o\u00f9 j\u2019ai obtenu un dipl\u00f4me en Business Administration et suivi des cours d\u2019histoire de l\u2019art\u00a0\u00bb, poursuit-il.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1346 size-full\" src=\"http:\/\/www.gentleman.be\/fr\/wp-content\/uploads\/2015\/01\/Web-Ch-Van-De-Weghe-3.jpg\" alt=\"Web Ch Van De Weghe 3\" width=\"600\" height=\"715\" \/><\/p>\n<p style=\"text-align: justify;\">La question d\u2019une reconversion se met alors \u00e0 le tarauder. Sans y avoir r\u00e9ellement r\u00e9fl\u00e9chi, il se sent attir\u00e9 par l\u2019art. Un hasard\u00a0? Pas vraiment. Le jeune homme qu\u2019il est alors a pour beau-p\u00e8re un certain Roger Nellens. Collectionneur, il appartient \u00e0 la famille qui a fait les beaux jours de Knokke par le biais de son Casino. Un Casino dans lequel des pointures comme Magritte, Delvaux ou Haring ont sign\u00e9 d\u2019impressionnantes fresques. Aujourd\u2019hui encore, la maison de Roger Nellens, au 280 de la Zoutelaan, fait place au \u00ab\u00a0Dragon\u00a0\u00bb, une sculpture \u00e0 habiter de Niki de Saint Phalle dans laquelle ont s\u00e9journ\u00e9 entre autre Keith Haring, encore lui, et Jean Tinguely. Il est \u00e9vident qu\u2019on ne grandit pas dans un tel contexte sans en \u00eatre marqu\u00e9.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Provoquer le destin<\/strong><\/h2>\n<p style=\"text-align: justify;\">Bien d\u00e9cid\u00e9 \u00e0 faire son chemin, Christophe Van\u00a0de\u00a0Weghe demande \u00e0 son p\u00e8re, marchand de tapis \u00e0 Bruxelles et \u00e0 Knokke, de lui am\u00e9nager une petite place dans l\u2019un de ses magasins pour qu\u2019il puisse y am\u00e9nager une galerie. L\u2019affaire est conclue, il se lance. Lors d\u2019un s\u00e9jour \u00e0 New York au moment des grandes ventes chez Christie\u2019s, le jeune galeriste rencontre Larry Gagosian, marchand d\u2019art d\u00e9j\u00e0 tr\u00e8s en vue. \u00ab\u00a0Je l\u2019ai f\u00e9licit\u00e9 pour le portrait de David Hockney qu\u2019il avait acquis quelques heures plus t\u00f4t. La conversation s\u2019est engag\u00e9e, Larry aimait beaucoup le fait que je joue au tennis, il envisageait d\u00e9j\u00e0 les parties en double qui lui permettraient de battre ses clients dans sa propri\u00e9t\u00e9 des Hamptons.\u00a0\u00bb Fort de cette perspective, Gagosian engage le Belge \u00e0 l\u2019essai, la condition ultime \u00e9tant bien s\u00fbr d\u2019obtenir des r\u00e9sultats \u00ab\u00a0A la fin de mon stage, j\u2019ai d\u00e9pos\u00e9 un ch\u00e8que de 50.000 dollars sur le bureau de Larry Gagosian. Il \u00e9tait ravi, il m\u2019a propos\u00e9 un salaire de 30.000 dollars par an plus les commissions. J\u2019ai saut\u00e9 de joie, j\u2019avais un peu plus de 20 ans. Trois ans plus tard, j\u2019\u00e9tais son premier vendeur. Au total, je suis rest\u00e9 7\u00a0ans avec lui. C\u2019est un tout grand, il m\u2019a donn\u00e9 ma chance et m\u2019a \u00e9norm\u00e9ment appris. Je le respecte beaucoup et suis toujours proche de lui.\u00a0\u00bb<\/p>\n<h2 style=\"text-align: justify;\"><strong>Valeurs s\u00fbres<\/strong><\/h2>\n<p style=\"text-align: justify;\">Il reste qu\u2019en bon vendeur s\u00fbr de son potentiel, Van\u00a0de\u00a0Weghe a des ambitions. Il r\u00eave de s\u2019\u00e9tablir \u00e0 son compte. Comme la fortune finit toujours par sourire aux audacieux, il apprend un jour de la bouche du marchand Per Skarstedt qu\u2019il va d\u00e9m\u00e9nager. \u00ab\u00a0C\u2019\u00e9tait une formidable opportunit\u00e9, un espace de 180 m\u00e8tres carr\u00e9s \u00e0 5.000 dollars. Le seul souci \u00e9tait de convaincre Larry, s\u2019il n\u2019avait pas \u00e9t\u00e9 d\u2019accord, je ne serais pas parti. A un moment de la conversation, je lui ai dit :\u00a0\u00ab\u00a0Larry, what would you do if you were my age\u00a0?\u00a0\u00bb\u2026 il m\u2019a donn\u00e9 sa b\u00e9n\u00e9diction\u00a0\u00bb, raconte Van de Weghe.<\/p>\n<p style=\"text-align: justify;\">La situation qu\u2019il occupe permet \u00e0 Christophe Van\u00a0de\u00a0Weghe de jeter un \u0153il avis\u00e9 sur le march\u00e9 de l\u2019art. Les derniers chiffres sortis sont \u00e0 la hausse, le march\u00e9 ayant pes\u00e9 quelque 12 milliards de dollars en 2013, ce qui r\u00e9jouit le galeriste. \u00ab\u00a0Il faut bien avoir conscience que j\u2019\u00e9volue dans un secteur particulier qui est celui du second march\u00e9. Qu\u2019il s\u2019agisse d\u2019art moderne ou d\u2019art contemporain, je ne traite que des valeurs s\u00fbres. Basquiat, Warhol, Richter\u2026 il n\u2019y a jamais de feu de paille. Si un artiste perd pendant un moment, il en vient toujours un autre o\u00f9 il se r\u00e9tablit.\u00a0Avec l\u2019immobilier, l\u2019art fait partie des refuges \u00e9conomiques. Surtout aujourd\u2019hui, \u00e0 l\u2019heure o\u00f9 le march\u00e9 est devenu plus globalis\u00e9 que jamais. Je le constate, j\u2019ai de plus en plus de clients qui viennent de partout dans le monde et qui sont de plus en plus jeunes. Acheter une toile de Francis Bacon ou Pablo Picasso revient \u00e0 appartenir \u00e0 un club ferm\u00e9. Sans compter que les prix ne font qu\u2019augmenter. Il est quasi impossible d\u2019acheter un beau Magritte \u00e0 moins de 10 millions de dollars, ce n\u2019\u00e9tait pas le cas avant.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Calder compte \u00e9galement parmi les artistes qui tiennent le galeriste \u00e0 c\u0153ur. \u00ab\u00a0Il fait partie des cinq plus grands sculpteurs du si\u00e8cle pass\u00e9. Pourtant lorsqu\u2019on le compare \u00e0 Giacometti dont \u00ab\u00a0L\u2019homme qui marche\u00a0\u00bb s\u2019est vendu \u00e0 110\u00a0millions de dollars, il est presque donn\u00e9. A la lueur de ce type de comparaison, il est clair que les \u0153uvres de Calder vont exploser\u00a0\u00bb, confie l\u2019int\u00e9ress\u00e9. Il ne tarit pas non plus d\u2019\u00e9loges sur Basquiat dont le travail aimante les jeunes et les vieux collectionneurs avec le m\u00eame magn\u00e9tisme.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1348 size-full\" src=\"http:\/\/www.gentleman.be\/fr\/wp-content\/uploads\/2015\/01\/Web-Ch-Van-De-Weghe-5.jpg\" alt=\"Web Ch Van De Weghe 5\" width=\"600\" height=\"750\" \/><\/p>\n<h2 style=\"text-align: justify;\"><strong>Homme de contact<\/strong><\/h2>\n<p style=\"text-align: justify;\">Les journ\u00e9es du marchand\u00a0? \u00ab\u00a0L\u2019important est d\u2019\u00eatre en contact avec les collectionneurs, raison pour laquelle je prends toujours mon petit-d\u00e9jeuner avec l\u2019un d\u2019entre eux, invariablement chez Sant Ambroeus, une adresse italienne sur Madison Avenue fr\u00e9quent\u00e9e par toute la profession. Larry Gagosian y a sa table. Je consacre le d\u00e9jeuner aux relations avec les autres galeristes afin d\u2019\u00eatre au courant de ce qui se passe. En revanche, les soir\u00e9es sont pour la famille, tout comme les week-ends que nous passons dans les Hamptons\u00a0\u00bb, explique celui qui compte l\u2019investisseur Daniel Loeb parmi ses clients.<\/p>\n<p style=\"text-align: justify;\">Quand on lui demande quelle est la qualit\u00e9 essentielle pour \u00eatre un bon galeriste, l\u2019ancien tennisman r\u00e9pond avec beaucoup de modestie \u00ab\u00a0\u00eatre au bon endroit\u00a0\u00bb, pr\u00e9cisant que \u00ab\u00a0New York reste la meilleure place forte du march\u00e9 de l\u2019art\u00a0\u00bb et qu\u2019il conna\u00eet \u00ab\u00a0des immeubles de l\u2019Upper East Side o\u00f9 l\u2019on ach\u00e8te plus que dans l\u2019ensemble de la Chine.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Tout est donc \u00e0 vendre dans ce bas-monde\u00a0? Pas forc\u00e9ment. \u00ab\u00a0Je pense qu\u2019un bon marchand se doit d\u2019avoir une collection personnelle. Il est essentiel pour moi de me mettre dans la peau du collectionneur et de comprendre sa fa\u00e7on de penser. Si j\u2019ach\u00e8te pour moi tel ou tel artiste, j\u2019ai \u00e9videmment plus de cr\u00e9dit aux yeux de mon client lorsque je lui conseille d\u2019acheter ce m\u00eame artiste. Avec Anne-Ga\u00eblle, mon \u00e9pouse, nous poss\u00e9dons un magnifique tableau de Cy Twombly de 1961 que nous voulons c\u00e9der \u00e0 nos enfants plus tard\u2026 cette \u0153uvre ne quittera sans doute pas notre famille.\u00a0\u00bb<br \/>\n<a title=\"Van de Weghe New York\" href=\"http:\/\/www.vdwny.com\/\" target=\"_blank\">www.vdwny.com<\/a><\/p>\n<p style=\"text-align: justify;\">Texte\u00a0: Michel Verlinden<br \/>\nArticle paru dans le <a href=\"http:\/\/www.gentleman.be\/fr\/page\/8\/\" target=\"_blank\">Gentleman<\/a> n\u00b0 3 \u2013 Printemps \/ Et\u00e9 2014<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>\u00ab If I can make it there, I\u2019ll make it anywhere \u00bb&#8230; On songe \u00e0 la chanson de Sinatra quand on s&rsquo;expose au fabuleux parcours de Christophe Van de Weghe. Le galeriste belge s&rsquo;est \u00e9tabli au sommet du march\u00e9 de l&rsquo;art o\u00f9 il c\u00f4toie les oeuvres de Ren\u00e9 Magritte, Joan Miro, Henri Matisse, Pablo Picasso, Paul Delvaux, Andy Wharhol&#8230; <\/p>\n","protected":false},"author":2,"featured_media":4357,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1128],"tags":[43],"class_list":["post-4168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rencontres","tag-culture"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Christophe Van de Weghe, sa success-story - Fifty &amp; Me MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christophe Van de Weghe, sa success-story - Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"Reading Time:  6 minutes\u00ab If I can make it there, I\u2019ll make it anywhere \u00bb... On songe \u00e0 la chanson de Sinatra quand on s&#039;expose au fabuleux parcours de Christophe Van de Weghe. Le galeriste belge s&#039;est \u00e9tabli au sommet du march\u00e9 de l&#039;art o\u00f9 il c\u00f4toie les oeuvres de Ren\u00e9 Magritte, Joan Miro, Henri Matisse, Pablo Picasso, Paul Delvaux, Andy Wharhol...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story\" \/>\n<meta property=\"og:site_name\" content=\"Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-21T14:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-12T11:11:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/06\/UNE-ART-Gallery-Life-Magazine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ga\u00eblle Mauroit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ga\u00eblle Mauroit\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story\",\"name\":\"Christophe Van de Weghe, sa success-story - Fifty &amp; Me MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/06\/UNE-ART-Gallery-Life-Magazine.jpg\",\"datePublished\":\"2015-08-21T14:00:28+00:00\",\"dateModified\":\"2018-03-12T11:11:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#primaryimage\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/06\/UNE-ART-Gallery-Life-Magazine.jpg\",\"contentUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/06\/UNE-ART-Gallery-Life-Magazine.jpg\",\"width\":600,\"height\":520,\"caption\":\"Copyright : littleny\/Shutterstock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Culture\",\"item\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rencontres\",\"item\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Christophe Van de Weghe, sa success-story\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/\",\"name\":\"Fifty &amp; Me MAGAZINE\",\"description\":\"Et si la vie commen\u00e7ait \u00e0 50 ans ?\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b\",\"name\":\"Ga\u00eblle Mauroit\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/gaelle\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Christophe Van de Weghe, sa success-story - Fifty &amp; Me MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story","og_locale":"fr_FR","og_type":"article","og_title":"Christophe Van de Weghe, sa success-story - Fifty &amp; Me MAGAZINE","og_description":"Reading Time:  6 minutes\u00ab If I can make it there, I\u2019ll make it anywhere \u00bb... On songe \u00e0 la chanson de Sinatra quand on s'expose au fabuleux parcours de Christophe Van de Weghe. Le galeriste belge s'est \u00e9tabli au sommet du march\u00e9 de l'art o\u00f9 il c\u00f4toie les oeuvres de Ren\u00e9 Magritte, Joan Miro, Henri Matisse, Pablo Picasso, Paul Delvaux, Andy Wharhol...","og_url":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story","og_site_name":"Fifty &amp; Me MAGAZINE","article_published_time":"2015-08-21T14:00:28+00:00","article_modified_time":"2018-03-12T11:11:09+00:00","og_image":[{"width":600,"height":520,"url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/06\/UNE-ART-Gallery-Life-Magazine.jpg","type":"image\/jpeg"}],"author":"Ga\u00eblle Mauroit","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ga\u00eblle Mauroit","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story","name":"Christophe Van de Weghe, sa success-story - Fifty &amp; Me MAGAZINE","isPartOf":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#primaryimage"},"image":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#primaryimage"},"thumbnailUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/06\/UNE-ART-Gallery-Life-Magazine.jpg","datePublished":"2015-08-21T14:00:28+00:00","dateModified":"2018-03-12T11:11:09+00:00","author":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b"},"breadcrumb":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#primaryimage","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/06\/UNE-ART-Gallery-Life-Magazine.jpg","contentUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/06\/UNE-ART-Gallery-Life-Magazine.jpg","width":600,"height":520,"caption":"Copyright : littleny\/Shutterstock"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres\/christophe-van-de-weghe-sa-success-story#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Culture","item":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture"},{"@type":"ListItem","position":2,"name":"Rencontres","item":"https:\/\/www.fiftyandmemagazine.be\/fr\/culture\/rencontres"},{"@type":"ListItem","position":3,"name":"Christophe Van de Weghe, sa success-story"}]},{"@type":"WebSite","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/","name":"Fifty &amp; Me MAGAZINE","description":"Et si la vie commen\u00e7ait \u00e0 50 ans ?","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b","name":"Ga\u00eblle Mauroit","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/gaelle"}]}},"modified_by":"Arnaud WOD","_links":{"self":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/4168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/comments?post=4168"}],"version-history":[{"count":0,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/4168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media\/4357"}],"wp:attachment":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media?parent=4168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/categories?post=4168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/tags?post=4168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}