{"id":43977,"date":"2019-12-07T12:14:06","date_gmt":"2019-12-07T11:14:06","guid":{"rendered":"https:\/\/www.fiftyandmemagazine.be\/fr\/?p=43977"},"modified":"2019-12-05T09:15:22","modified_gmt":"2019-12-05T08:15:22","slug":"decouvrez-les-bienfaits-de-leau-froide","status":"publish","type":"post","link":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide","title":{"rendered":"D\u00e9couvrez les bienfaits de l\u2019eau froide"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><h2><strong>Une amie qui ne peut vous laisser froid<\/strong><\/h2>\n<p>D\u2019accord, avec les temp\u00e9ratures hivernales que nous connaissons, vous r\u00eavez davantage d\u2019un bon bain chaud pour vous r\u00e9chauffer, de retour du boulot ou de la s\u00e9ance de <a href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/se-mettre-au-sport-a-50-ans-ils-lont-fait\" target=\"_blank\" rel=\"noopener noreferrer\">sport<\/a>. Vanter les avantages de l\u2019eau froide peut sembler insens\u00e9. Certes, mais vous changerez certainement d\u2019avis \u00e0 la d\u00e9couverte des avantages r\u00e9colt\u00e9s pour votre bien-\u00eatre corporel. Une eau froide dont les effets seront rapidement visibles. A condition de d\u00e9passer ses appr\u00e9hensions.<br \/>\nUne forme d\u2019hydroth\u00e9rapie dont la diffusion est attribu\u00e9e \u00e0 l\u2019abb\u00e9 allemand S\u00e9bastien Kneipp. Malade, il avait d\u00e9couvert que l\u2019eau froide lui faisait du bien. Un pionnier dont les travaux sont unanimement c\u00e9l\u00e9br\u00e9s aujourd\u2019hui. Par vous aussi, peut-\u00eatre. Apr\u00e8s un essai concluant.<\/p>\n<h2><strong>Un choc thermique qui se pr\u00e9pare<\/strong><\/h2>\n<p>Certains principes sont \u00e0 prendre en compte, pour \u00e9viter des d\u00e9sagr\u00e9ments pour votre sant\u00e9 ou votre envie de poursuivre\u00a0:<\/p>\n<ul>\n<li>Commencez avec de l\u2019eau \u00e0 16 ou 18\u00b0C. Au fil des s\u00e9ances, diminuez ensuite la temp\u00e9rature pour atteindre les 8\u00b0C, soit de l\u2019eau qualifi\u00e9e de bien froide.<\/li>\n<li>Plus l\u2019eau est froide, plus courtes seront les applications. Trois minutes de moyenne.<\/li>\n<li>Votre salle de bains doit \u00eatre chauff\u00e9e (aux environs de 20\u00b0C)<\/li>\n<li>Le moment id\u00e9al est de vous laver au lever ou apr\u00e8s le sport, quand votre corps sera bien chaud. Mais pas avant 3 heures apr\u00e8s la prise d\u2019un repas.<\/li>\n<li>On ne se frictionne pas, on se mouille \u00e0 l\u2019eau froide. Et on ne s\u2019essuie pas.<\/li>\n<li>Le bain complet sera pris apr\u00e8s un certain endurcissement. Et pas plus que deux fois par semaine.<\/li>\n<\/ul>\n<h2><strong>Les bienfaits de l&rsquo;eau froide<\/strong><\/h2>\n<p>Si l\u2019on garde de la douche glac\u00e9e l\u2019image d\u2019un traitement radical pour calmer les esprits agit\u00e9s, elle offre pourtant plus d\u2019un avantage. Jugez-en\u00a0:<\/p>\n<ul>\n<li>Un effet anti-<a href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/menopause\/menoptimiste-5-conseils-anti-fatigue-lors-de-la-menopause\" target=\"_blank\" rel=\"noopener noreferrer\">fatigue<\/a> d\u00e8s le lever. Elle booste votre organisme d\u00e8s le lever.<\/li>\n<li>Une protection musculaire apr\u00e8s l\u2019effort<\/li>\n<li>Un renforcement du syst\u00e8me immunitaire par l\u2019activation, due au froid, de globules blancs<\/li>\n<li>Bienfait constat\u00e9 en cas d\u2019\u00e9tat d\u00e9pressif ou de mal-\u00eatre par la production de neurotransmetteurs<\/li>\n<li>Assurance d\u2019une meilleure circulation sanguine. Avec, notamment, la diminution des varices.<\/li>\n<li>Une solution efficace contre les maux de t\u00eate. Sur le front et les tempes douloureux, appliquez de l\u2019eau froide en massant doucement.<\/li>\n<li>L\u2019eau froide agit sur la perte de calories. Pour maintenir sa temp\u00e9rature de 37\u00b0C, le corps va devoir produire de l\u2019\u00e9nergie et donc br\u00fbler des calories.<\/li>\n<li>Raffermissement des <a href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/3-astuces-pour-se-raffermir-sans-faire-de-sport\" target=\"_blank\" rel=\"noopener noreferrer\">muscles<\/a> et un puissant tonifiant. A conseiller, le jet d\u2019eau sur les seins.<\/li>\n<li>Pour le visage, pr\u00e9f\u00e9rez de l\u2019eau froide en spray si l\u2019eau est trop \u00ab\u00a0dure\u00a0\u00bb. Ne pas essuyer le visage apr\u00e8s le nettoyage. L\u2019eau froide va r\u00e9duire les rides et resserrer les pores du visage. Donc limiter les risques d\u2019acn\u00e9, pr\u00e9sents \u00e0 50 ans aussi.<\/li>\n<li>Un rin\u00e7age des <a href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/cheveux\/quelle-coupe-de-cheveux-choisir-pour-une-femme-a-50-ans\" target=\"_blank\" rel=\"noopener noreferrer\">cheveux<\/a> \u00e0 l\u2019eau froide les rendra plus brillants. Contrairement \u00e0 l\u2019eau chaude.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Une amie qui ne peut vous laisser froid D\u2019accord, avec [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":43978,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"categories":[1110],"tags":[],"class_list":["post-43977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-garder-la-forme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9couvrez les bienfaits de l\u2019eau froide - Fifty &amp; Me MAGAZINE<\/title>\n<meta name=\"description\" content=\"L\u2019eau, impossible de s\u2019en passer. On la boit pure, on l\u2019utilise en thalasso. Mais connaissez-vous les bienfaits de l&#039;eau froide?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9couvrez les bienfaits de l\u2019eau froide - Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"L\u2019eau, impossible de s\u2019en passer. On la boit pure, on l\u2019utilise en thalasso. Mais connaissez-vous les bienfaits de l&#039;eau froide?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide\" \/>\n<meta property=\"og:site_name\" content=\"Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-07T11:14:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2019\/12\/bienfaits_de_l_eau_froide.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1110\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lauren Soukiassian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lauren Soukiassian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide\",\"name\":\"D\u00e9couvrez les bienfaits de l\u2019eau froide - Fifty &amp; Me MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2019\/12\/bienfaits_de_l_eau_froide.jpg\",\"datePublished\":\"2019-12-07T11:14:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/ebc87c29599dd51d1bb53bc5a497e45d\"},\"description\":\"L\u2019eau, impossible de s\u2019en passer. On la boit pure, on l\u2019utilise en thalasso. Mais connaissez-vous les bienfaits de l'eau froide?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#primaryimage\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2019\/12\/bienfaits_de_l_eau_froide.jpg\",\"contentUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2019\/12\/bienfaits_de_l_eau_froide.jpg\",\"width\":1110,\"height\":500,\"caption\":\"bienfaits de l'eau froide\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Sant\u00e9\",\"item\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garder la forme\",\"item\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00e9couvrez les bienfaits de l\u2019eau froide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/\",\"name\":\"Fifty &amp; Me MAGAZINE\",\"description\":\"Et si la vie commen\u00e7ait \u00e0 50 ans ?\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/ebc87c29599dd51d1bb53bc5a497e45d\",\"name\":\"Lauren Soukiassian\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/lauren\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9couvrez les bienfaits de l\u2019eau froide - Fifty &amp; Me MAGAZINE","description":"L\u2019eau, impossible de s\u2019en passer. On la boit pure, on l\u2019utilise en thalasso. Mais connaissez-vous les bienfaits de l'eau froide?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9couvrez les bienfaits de l\u2019eau froide - Fifty &amp; Me MAGAZINE","og_description":"L\u2019eau, impossible de s\u2019en passer. On la boit pure, on l\u2019utilise en thalasso. Mais connaissez-vous les bienfaits de l'eau froide?","og_url":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide","og_site_name":"Fifty &amp; Me MAGAZINE","article_published_time":"2019-12-07T11:14:06+00:00","og_image":[{"width":1110,"height":500,"url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2019\/12\/bienfaits_de_l_eau_froide.jpg","type":"image\/jpeg"}],"author":"Lauren Soukiassian","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lauren Soukiassian","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide","name":"D\u00e9couvrez les bienfaits de l\u2019eau froide - Fifty &amp; Me MAGAZINE","isPartOf":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#primaryimage"},"image":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#primaryimage"},"thumbnailUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2019\/12\/bienfaits_de_l_eau_froide.jpg","datePublished":"2019-12-07T11:14:06+00:00","author":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/ebc87c29599dd51d1bb53bc5a497e45d"},"description":"L\u2019eau, impossible de s\u2019en passer. On la boit pure, on l\u2019utilise en thalasso. Mais connaissez-vous les bienfaits de l'eau froide?","breadcrumb":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#primaryimage","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2019\/12\/bienfaits_de_l_eau_froide.jpg","contentUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2019\/12\/bienfaits_de_l_eau_froide.jpg","width":1110,"height":500,"caption":"bienfaits de l'eau froide"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme\/decouvrez-les-bienfaits-de-leau-froide#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Sant\u00e9","item":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante"},{"@type":"ListItem","position":2,"name":"Garder la forme","item":"https:\/\/www.fiftyandmemagazine.be\/fr\/sante\/garder-la-forme"},{"@type":"ListItem","position":3,"name":"D\u00e9couvrez les bienfaits de l\u2019eau froide"}]},{"@type":"WebSite","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/","name":"Fifty &amp; Me MAGAZINE","description":"Et si la vie commen\u00e7ait \u00e0 50 ans ?","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/ebc87c29599dd51d1bb53bc5a497e45d","name":"Lauren Soukiassian","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/lauren"}]}},"modified_by":"Magali Duqu\u00e9","_links":{"self":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/43977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/comments?post=43977"}],"version-history":[{"count":2,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/43977\/revisions"}],"predecessor-version":[{"id":43980,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/43977\/revisions\/43980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media\/43978"}],"wp:attachment":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media?parent=43977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/categories?post=43977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/tags?post=43977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}