{"id":4765,"date":"2015-07-10T19:37:02","date_gmt":"2015-07-10T17:37:02","guid":{"rendered":"http:\/\/www.life-magazine.be\/fr\/?p=4765"},"modified":"2019-05-28T11:46:53","modified_gmt":"2019-05-28T09:46:53","slug":"le-soleil-notre-meilleur-ennemi","status":"publish","type":"post","link":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi","title":{"rendered":"Le soleil, notre meilleur ennemi"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p style=\"text-align: justify;\"><strong><span style=\"color: #ff6600;\">M<\/span>algr\u00e9 les campagnes de pr\u00e9vention et l&rsquo;inflation des indices UV sur les flacons des cr\u00e8mes solaires depuis une vingtaine d\u2019ann\u00e9es, le nombre de m\u00e9lanomes ne cesse d\u2019augmenter en Belgique. Si 93\u00a0% des Belges savent que le soleil peut \u00eatre \u00e0 l\u2019origine de probl\u00e8mes de sant\u00e9 et qu\u2019il acc\u00e9l\u00e8re le vieillissement de la peau, beaucoup continuent \u00e0 mal se prot\u00e9ger et \u00e0 n\u00e9gliger de faire examiner leurs grains de beaut\u00e9 par un dermatologue<sup>1<\/sup>.<\/strong><\/p>\n<p style=\"text-align: right;\"><em>\u00a0Par Isabelle Blandiaux<\/em><\/p>\n<p style=\"text-align: justify;\">Est-ce le fait d\u2019en \u00eatre priv\u00e9 durant de longs mois de l\u2019ann\u00e9e qui emp\u00eache beaucoup de Belges d&rsquo;adopter \u00e0 l&rsquo;\u00e9gard du soleil un comportement raisonn\u00e9 ? Selon une r\u00e9cente enqu\u00eate, 1,72\u00a0% de nos compatriotes refuse de rentrer de vacances sans bronzage, toujours jug\u00e9 tr\u00e8s attractif. Et ils sont 18\u00a0% \u00e0 croire qu&rsquo;il n&rsquo;est plus n\u00e9cessaire d&rsquo;appliquer une protection solaire lorsqu&rsquo;on est d\u00e9j\u00e0 bronz\u00e9, tandis que 63\u00a0% pensent qu&rsquo;un SPF 50+ est r\u00e9serv\u00e9 aux profils \u00e0 risque. \u00ab\u00a0Nous ne disons pas qu&rsquo;il faut fuir le soleil, qui apporte beaucoup de bien-\u00eatre et permet au corps de synth\u00e9tiser sa dose quotidienne de vitamine D (une exposition des avant-bras de 30 minutes environ suffit)\u00a0\u00bb, pr\u00e9cise le docteur Nathalie Rooseleer, dermatologue vice-pr\u00e9sidente d\u2019Euromelanoma Belgique<sup>2<\/sup> et consultante au CHU Saint-Pierre. \u00ab\u00a0Mais le bronzage est une tentative de protection insuffisante de la peau puisque l\u2019exposition solaire devient canc\u00e9rig\u00e8ne si on en abuse. L\u2019id\u00e9e, c\u2019est de s\u2019exposer progressivement, prudemment pour que ce soit b\u00e9n\u00e9fique.\u00a0Tout d\u00e9pend \u00e9videmment du type de peau, mais \u00e0 part les M\u00e9diterran\u00e9ens \u00e0 la peau mate ou les Africains, tous ceux qui ont une peau plus claire, y compris m\u00e9tiss\u00e9e avec des cheveux fonc\u00e9s, doivent se prot\u00e9ger avec minutie d\u00e8s la petite enfance.\u00a0\u00bb<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4773\" src=\"http:\/\/www.life-magazine.be\/fr\/wp-content\/uploads\/2015\/07\/couv-maillot-de-bain-life-magazine.jpg\" alt=\"couv-maillot-de-bain-life-magazine\" width=\"1309\" height=\"900\" srcset=\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/couv-maillot-de-bain-life-magazine.jpg 1309w, https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/couv-maillot-de-bain-life-magazine-768x528.jpg 768w, https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/couv-maillot-de-bain-life-magazine-315x217.jpg 315w\" sizes=\"auto, (max-width: 1309px) 100vw, 1309px\" \/><\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #333333;\">Life Magazine\u00a0: les chiffres de la mortalit\u00e9 li\u00e9e au cancer de la peau et le nombre de cas de m\u00e9lanomes ne diminuent pas en Belgique. Faut-il en conclure que les messages de pr\u00e9vention sont inefficaces\u00a0?<\/span><\/h4>\n<p style=\"text-align: justify;\">Nathalie Rooseleer\u00a0: Il y a encore trop de personnes qui prennent des risques par rapport \u00e0 l\u2019exposition au soleil. Et les b\u00e9n\u00e9fices de la pr\u00e9vention ne se font parfois sentir que des ann\u00e9es plus tard, mais le but est d\u2019enlever des m\u00e9lanomes de plus en plus fins, \u00e0 un stade plus d\u00e9butant. Le risque de d\u00e9velopper un m\u00e9lanome \u00e0 l\u2019\u00e2ge adulte se prend surtout pendant l\u2019enfance et l\u2019adolescence, sous la forme de coups de soleil. Quant aux carcinomes, ils sont plut\u00f4t favoris\u00e9s par une exposition chronique au soleil sans protection suffisante, m\u00eame sans coup de soleil. Le m\u00e9lanome est le cancer de la peau le plus mortel mais on le gu\u00e9rit dans environ 75\u00a0% des cas. En Australie, o\u00f9 le taux de m\u00e9lanomes est quatre fois plus important que chez nous, ils prennent des mesures drastiques par rapport au soleil depuis d\u00e9j\u00e0 plus de trente ans (les enfants doivent notamment porter un chapeau dans les \u00e9coles)\u00a0: on y a assist\u00e9 \u00e0 une diminution de la mortalit\u00e9 due aux cancers de la peau ces derni\u00e8res ann\u00e9es.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #333333;\">La campagne d\u2019Euromelanoma<sup>2<\/sup> est ax\u00e9e cette ann\u00e9e sur le d\u00e9lai de r\u00e9action en cas de tache suspecte. Pourquoi\u00a0?<\/span><\/h4>\n<p style=\"text-align: justify;\">N.R.\u00a0: Aussi bien pour le carcinome que le m\u00e9lanome, si le diagnostic est pr\u00e9coce, on gu\u00e9rit d\u2019un cancer de la peau, apr\u00e8s une petite intervention chirurgicale. Au-del\u00e0 d\u2019un certain d\u00e9lai qui d\u00e9pend de l\u2019agressivit\u00e9 de la tumeur et de l\u2019immunit\u00e9 de la personne, l\u00e0, on risque de devoir utiliser des th\u00e9rapies cibl\u00e9es pour le m\u00e9lanome ou de l\u2019immunoth\u00e9rapie mais qui ne garantissent pas une gu\u00e9rison \u00e0 100\u00a0%.<\/p>\n<p style=\"text-align: justify;\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4774\" src=\"http:\/\/www.life-magazine.be\/fr\/wp-content\/uploads\/2015\/07\/de-la-peau-life-magazine.jpg\" alt=\"_de-la-peau-life-magazine\" width=\"600\" height=\"520\" srcset=\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/de-la-peau-life-magazine.jpg 600w, https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/de-la-peau-life-magazine-160x139.jpg 160w, https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/de-la-peau-life-magazine-315x273.jpg 315w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #333333;\">Vous pr\u00f4nez l\u2019auto-d\u00e9pistage, qui serait pratiqu\u00e9 par 33\u00a0% des Belges, tandis qu\u2019un Belge sur deux n\u2019aurait jamais fait examiner ses grains de beaut\u00e9 par un dermatologue.<\/span><\/h4>\n<p style=\"text-align: justify;\">\u00a0N.R.\u00a0: L\u2019id\u00e9e est de former les gens \u00e0 l\u2019auto-d\u00e9pistage comme pour le cancer du sein. On peut suivre la r\u00e8gle de l\u2019ABCDE pour d\u00e9tecter les taches qui sont Asym\u00e9triques, avec des Bords irr\u00e9guliers, qui changent de Couleur, qui ont une Diam\u00e8tre de plus de 6 mm et Evoluent en termes de forme, de taille ou de couleur. On s\u2019auto-examine avec un miroir ou en demandant de l\u2019aide \u00e0 un compagnon ou une compagne, et \u00e0 la moindre l\u00e9sion suspecte, on consulte soit son dermatologue soit un g\u00e9n\u00e9raliste qui peut orienter vers le dermatologue s\u2019il confirme l\u2019inqui\u00e9tude. Mais on n\u2019est pas m\u00e9decin soi-m\u00eame et il y a toujours des zones qui \u00e9chappent \u00e0 la vue. C\u2019est donc toujours int\u00e9ressant de faire un examen annuel chez le dermatologue ou un premier examen qui permettra au dermatologue de vous dire si c\u2019est important pour vous de le faire annuellement ou pas.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #333333;\">A quel rythme l\u2019auto-examen devrait-il se faire id\u00e9alement\u00a0?<\/span><\/h4>\n<p style=\"text-align: justify;\">\u00a0N.R.\u00a0: Si on a une peau tr\u00e8s \u00e0 risque, claire avec des coups de soleil dans l\u2019enfance, ou qu\u2019on a v\u00e9cu dans un pays ensoleill\u00e9, on recommande un auto-examen tous les mois ou les deux mois, en utilisant un miroir ou en demandant l\u2019aide d\u2019un compagnon ou d\u2019une compagne.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #333333;\">Environ 80\u00a0% des dommages caus\u00e9s par le soleil \u00e0 la peau surviennent avant l\u2019\u00e2ge de 18\u00a0ans. Est-ce li\u00e9 \u00e0 la finesse de la peau \u00e0 cette p\u00e9riode\u00a0?<\/span><\/h4>\n<p style=\"text-align: justify;\">\u00a0N.R.\u00a0: Non, c\u2019est plus complexe mais c\u2019est une p\u00e9riode fragile o\u00f9 le soleil ab\u00eeme l\u2019ADN des cellules cutan\u00e9es plus fortement. Les \u00e9tudes \u00e9pid\u00e9miologiques, c\u2019est-\u00e0-dire qui \u00e9tudient les risques par rapport aux personnes qui ont un cancer de la peau \u00e0 l\u2019\u00e2ge adulte, \u00e9tablissent une corr\u00e9lation avec le fait d\u2019avoir eu des coups de soleil dans l\u2019enfance ou \u00e0 l\u2019adolescence. L\u2019abus de soleil est un facteur de risque prouv\u00e9 pour les m\u00e9lanomes et les carcinomes mais il arrive plus rarement qu\u2019on d\u00e9veloppe un m\u00e9lanome sur une zone non expos\u00e9e comme la zone g\u00e9nitale ou la plante des pieds. Il y a donc d\u2019autres facteurs de risques \u00e0 identifier, dont des facteurs g\u00e9n\u00e9tiques.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #333333;\">Quelles sont les zones du corps ou du visage auxquelles il faut \u00eatre particuli\u00e8rement attentif quand on se prot\u00e8ge du soleil\u00a0?<\/span><\/h4>\n<p style=\"text-align: justify;\">\u00a0N.R.\u00a0: Le m\u00e9lanome est plus fr\u00e9quent au niveau du dos chez les hommes et des jambes chez les femmes, en corr\u00e9lation avec l\u2019abus de soleil. On veillera \u00e0 garder son T-shirt, \u00e0 prot\u00e9ger le tronc, les \u00e9paules, la nuque, les oreilles. Les carcinomes sont plus fr\u00e9quents au niveau de la t\u00eate et du cou puisqu\u2019ils sont corr\u00e9l\u00e9s \u00e0 une exposition chronique. Donc ne pas oublier le chapeau, surtout chez les messieurs d\u00e9garnis mais aussi les enfants parce que le cuir chevelu peut \u00eatre atteint.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4777\" src=\"http:\/\/www.life-magazine.be\/fr\/wp-content\/uploads\/2015\/07\/3803_l-life-magazine.jpg\" alt=\"3803_l-life-magazine\" width=\"886\" height=\"768\" srcset=\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/3803_l-life-magazine.jpg 886w, https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/3803_l-life-magazine-160x139.jpg 160w, https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/3803_l-life-magazine-768x666.jpg 768w, https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/3803_l-life-magazine-315x273.jpg 315w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #333333;\">Quelles r\u00e8gles de vie adopter pour prot\u00e9ger les enfants et les adolescents, puisqu\u2019une bonne protection solaire est recommand\u00e9e toute l\u2019ann\u00e9e et pas seulement durant les vacances\u00a0?<\/span><\/h4>\n<p style=\"text-align: justify;\">\u00a0N.R.\u00a0: Avant 3 ans, pas d\u2019exposition directe, donc les couvrir, leur mettre chapeau, lunettes et cr\u00e8me solaire d\u2019un indice 50 adapt\u00e9e, contenant des \u00e9crans min\u00e9raux moins toxiques potentiellement puisqu\u2019ils ne sont quasi pas absorb\u00e9s. Ils refl\u00e8tent le soleil et sont donc plus blancs, ce qui peut \u00eatre consid\u00e9r\u00e9 comme un d\u00e9savantage pour les adultes mais comme un avantage pour les enfants puisqu\u2019on voit mieux o\u00f9 on applique la cr\u00e8me. Apr\u00e8s 3 ans, on reste \u00e9videmment prudent et on garde un indice 50 jusqu\u2019\u00e0 12\u00a0ans. On adapte son comportement en fonction du type de peau, toujours en \u00e9vitant le coup de soleil qui doit \u00eatre consid\u00e9r\u00e9 comme une sonnette d\u2019alarme, le fait qu\u2019on est all\u00e9 trop loin dans l\u2019exposition solaire. Il faudrait mieux sensibiliser les \u00e9coles. La meilleure protection reste le v\u00eatement, un T-shirt \u00e0 mailles serr\u00e9es pour la Belgique et \u00e9ventuellement un T-shirt sp\u00e9cifique anti-UV pour les pays tropicaux. L\u2019\u00e9cran dit total laisse passer quelques pourcents d\u2019UV qui permettent d\u2019avoir bonne mine mais ne prot\u00e8gent pas \u00e0 100\u00a0%. Pour atteindre les 98\u00a0% de protection avec l\u2019indice 50, il faut en appliquer une bonne couche toutes les deux heures.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #333333;\">Un quart de tube de 125 ml pour tout le corps, toutes les 2 heures, c\u2019est une norme peu suivie dans la pratique&#8230;<\/span><\/h4>\n<p style=\"text-align: justify;\">\u00a0N.R.\u00a0: Elle a \u00e9t\u00e9 calcul\u00e9e pour garantir la protection. Mais en Belgique, il y a toujours moyen de se mettre \u00e0 l\u2019ombre ou \u00e0 l\u2019int\u00e9rieur apr\u00e8s 2 heures d\u2019exposition dans son jardin ou en ville. L\u2019exposition solaire est souvent beaucoup plus intense en vacances, donc la cr\u00e8me solaire doit alors \u00eatre mise de fa\u00e7on plus assidue et r\u00e9guli\u00e8re (elle s\u2019\u00e9vapore naturellement, on transpire&#8230;) en \u00e9vitant le soleil aux heures de midi (entre 12h et 15h). Mes patients me disent souvent qu\u2019il leur est difficile de remettre de la cr\u00e8me toutes les deux heures, je leur conseille d\u00e8s lors de choisir un indice plus \u00e9lev\u00e9 et de ne pas trop prolonger l\u2019exposition au soleil.<\/p>\n<hr \/>\n<ol>\n<li style=\"text-align: justify;\"><em>Enqu\u00eate r\u00e9alis\u00e9e par Ipsos et La Roche-Posay du 3\/12\/14 au 8\/1\/15 dans 23\u00a0pays dont la Belgique, aupr\u00e8s de 19.569 personnes (500 \u00e0 1.000 par pays) \u00e2g\u00e9es de 15 \u00e0 65 ans.<\/em><\/li>\n<li style=\"text-align: justify;\"><em>Association paneurop\u00e9enne de pr\u00e9vention du cancer de la peau\u00a0: <a href=\"http:\/\/www.euromelanoma.org\" target=\"_blank\" rel=\"noopener noreferrer\">www.euromelanoma.org<\/a><\/em><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Malgr\u00e9 les campagnes de pr\u00e9vention et l&rsquo;inflation des indices UV sur les flacons des cr\u00e8mes solaires, le nombre de m\u00e9lanomes ne cesse d\u2019augmenter en Belgique. Est-ce le fait d\u2019en \u00eatre priv\u00e9 durant de longs mois de l\u2019ann\u00e9e qui emp\u00eache beaucoup de Belges d&rsquo;adopter \u00e0 l&rsquo;\u00e9gard du soleil un comportement raisonn\u00e9 ? Le docteur Nathalie Rooseleer, dermatologue vice-pr\u00e9sidente d\u2019Euromelanoma Belgique et consultante au CHU Saint-Pierre, nous \u00e9claire ! <\/p>\n","protected":false},"author":2,"featured_media":4770,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[3],"tags":[33],"class_list":["post-4765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bien-etre","tag-sante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le soleil, notre meilleur ennemi - Fifty &amp; Me MAGAZINE<\/title>\n<meta name=\"description\" content=\"Malgr\u00e9 les campagnes de pr\u00e9vention et l&#039;inflation des indices UV sur les flacons des cr\u00e8mes solaires, le nombre de m\u00e9lanomes ne cesse d\u2019augmenter en Belgique. Est-ce le fait d\u2019en \u00eatre priv\u00e9 durant de longs mois de l\u2019ann\u00e9e qui emp\u00eache beaucoup de Belges d&#039;adopter \u00e0 l&#039;\u00e9gard du soleil un comportement raisonn\u00e9 ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le soleil, notre meilleur ennemi - Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"Malgr\u00e9 les campagnes de pr\u00e9vention et l&#039;inflation des indices UV sur les flacons des cr\u00e8mes solaires, le nombre de m\u00e9lanomes ne cesse d\u2019augmenter en Belgique. Est-ce le fait d\u2019en \u00eatre priv\u00e9 durant de longs mois de l\u2019ann\u00e9e qui emp\u00eache beaucoup de Belges d&#039;adopter \u00e0 l&#039;\u00e9gard du soleil un comportement raisonn\u00e9 ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi\" \/>\n<meta property=\"og:site_name\" content=\"Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-10T17:37:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-28T09:46:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/alaune-soleil-life-magazine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ga\u00eblle Mauroit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ga\u00eblle Mauroit\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi\",\"name\":\"Le soleil, notre meilleur ennemi - Fifty &amp; Me MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/alaune-soleil-life-magazine.jpg\",\"datePublished\":\"2015-07-10T17:37:02+00:00\",\"dateModified\":\"2019-05-28T09:46:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b\"},\"description\":\"Malgr\u00e9 les campagnes de pr\u00e9vention et l'inflation des indices UV sur les flacons des cr\u00e8mes solaires, le nombre de m\u00e9lanomes ne cesse d\u2019augmenter en Belgique. Est-ce le fait d\u2019en \u00eatre priv\u00e9 durant de longs mois de l\u2019ann\u00e9e qui emp\u00eache beaucoup de Belges d'adopter \u00e0 l'\u00e9gard du soleil un comportement raisonn\u00e9 ?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#primaryimage\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/alaune-soleil-life-magazine.jpg\",\"contentUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/alaune-soleil-life-magazine.jpg\",\"width\":600,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Bien-\u00catre\",\"item\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le soleil, notre meilleur ennemi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/\",\"name\":\"Fifty &amp; Me MAGAZINE\",\"description\":\"Et si la vie commen\u00e7ait \u00e0 50 ans ?\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b\",\"name\":\"Ga\u00eblle Mauroit\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/gaelle\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le soleil, notre meilleur ennemi - Fifty &amp; Me MAGAZINE","description":"Malgr\u00e9 les campagnes de pr\u00e9vention et l'inflation des indices UV sur les flacons des cr\u00e8mes solaires, le nombre de m\u00e9lanomes ne cesse d\u2019augmenter en Belgique. Est-ce le fait d\u2019en \u00eatre priv\u00e9 durant de longs mois de l\u2019ann\u00e9e qui emp\u00eache beaucoup de Belges d'adopter \u00e0 l'\u00e9gard du soleil un comportement raisonn\u00e9 ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi","og_locale":"fr_FR","og_type":"article","og_title":"Le soleil, notre meilleur ennemi - Fifty &amp; Me MAGAZINE","og_description":"Malgr\u00e9 les campagnes de pr\u00e9vention et l'inflation des indices UV sur les flacons des cr\u00e8mes solaires, le nombre de m\u00e9lanomes ne cesse d\u2019augmenter en Belgique. Est-ce le fait d\u2019en \u00eatre priv\u00e9 durant de longs mois de l\u2019ann\u00e9e qui emp\u00eache beaucoup de Belges d'adopter \u00e0 l'\u00e9gard du soleil un comportement raisonn\u00e9 ?","og_url":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi","og_site_name":"Fifty &amp; Me MAGAZINE","article_published_time":"2015-07-10T17:37:02+00:00","article_modified_time":"2019-05-28T09:46:53+00:00","og_image":[{"width":600,"height":520,"url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/alaune-soleil-life-magazine.jpg","type":"image\/jpeg"}],"author":"Ga\u00eblle Mauroit","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ga\u00eblle Mauroit","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi","name":"Le soleil, notre meilleur ennemi - Fifty &amp; Me MAGAZINE","isPartOf":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#primaryimage"},"image":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#primaryimage"},"thumbnailUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/alaune-soleil-life-magazine.jpg","datePublished":"2015-07-10T17:37:02+00:00","dateModified":"2019-05-28T09:46:53+00:00","author":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b"},"description":"Malgr\u00e9 les campagnes de pr\u00e9vention et l'inflation des indices UV sur les flacons des cr\u00e8mes solaires, le nombre de m\u00e9lanomes ne cesse d\u2019augmenter en Belgique. Est-ce le fait d\u2019en \u00eatre priv\u00e9 durant de longs mois de l\u2019ann\u00e9e qui emp\u00eache beaucoup de Belges d'adopter \u00e0 l'\u00e9gard du soleil un comportement raisonn\u00e9 ?","breadcrumb":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#primaryimage","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/alaune-soleil-life-magazine.jpg","contentUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/07\/alaune-soleil-life-magazine.jpg","width":600,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre\/le-soleil-notre-meilleur-ennemi#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Bien-\u00catre","item":"https:\/\/www.fiftyandmemagazine.be\/fr\/bien-etre"},{"@type":"ListItem","position":2,"name":"Le soleil, notre meilleur ennemi"}]},{"@type":"WebSite","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/","name":"Fifty &amp; Me MAGAZINE","description":"Et si la vie commen\u00e7ait \u00e0 50 ans ?","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b","name":"Ga\u00eblle Mauroit","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/gaelle"}]}},"modified_by":"Magali Duqu\u00e9","_links":{"self":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/4765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/comments?post=4765"}],"version-history":[{"count":1,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/4765\/revisions"}],"predecessor-version":[{"id":40930,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/4765\/revisions\/40930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media\/4770"}],"wp:attachment":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media?parent=4765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/categories?post=4765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/tags?post=4765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}