{"id":8506,"date":"2016-01-27T07:40:42","date_gmt":"2016-01-27T06:40:42","guid":{"rendered":"http:\/\/www.life-magazine.be\/fr\/?p=8506"},"modified":"2018-03-07T15:13:30","modified_gmt":"2018-03-07T14:13:30","slug":"belles-belles-belles","status":"publish","type":"post","link":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles","title":{"rendered":"Belles, belles, belles"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p style=\"text-align: justify;\"><strong><span style=\"color: #ff6600;\">D<\/span><span style=\"color: #333333;\">an<\/span><span style=\"color: #333333;\">s le cadre de notre dossier sur \u00ab\u00a0la beaut\u00e9 en pharmacie\u00a0\u00bb, Life Magazine donne la parole aux femmes. Ravissantes de l\u2019int\u00e9rieur comme de l\u2019ext\u00e9rieur, elles nous signifient leur propre d\u00e9finition de la beaut\u00e9.\u00a0<\/span><\/strong><\/p>\n<h1><span style=\"color: #ff6600;\">\u00ab\u00a0La beaut\u00e9 est li\u00e9e \u00e0 une vie saine\u00a0\u00bb<\/span><\/h1>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\"><strong>M\u00e9lanie Dewulf, 39 ans<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0La beaut\u00e9 passe pour moi par un \u00e9quilibre entre le physique et le mental. Elle est li\u00e9e \u00e0 une vie saine\u00a0: combiner le rythme fou du travail avec sa vie priv\u00e9e, ne pas passer trop de temps sur les r\u00e9seaux sociaux mais faire du sport et avoir une alimentation saine, se pr\u00e9server assez d\u2019heures d\u2019un sommeil r\u00e9parateur avec des horaires r\u00e9guliers&#8230; Tout cela se voit sur le visage, parce qu\u2019on irradie. Je ne suis pas tr\u00e8s sportive mais je m\u2019impose des abdos tous les jours, je pratique le golf et j\u2019ai un coach \u00e0 domicile une fois par semaine. J\u2019adore les soins que j\u2019ach\u00e8te toujours \u00e0 la pharmacie pr\u00e8s de chez moi, mais ma peau est vite satur\u00e9e, donc je garde la main l\u00e9g\u00e8re. Idem, je ne me maquille quasi pas\u00a0parce que je ne me reconnais pas avec du maquillage. Je mets juste un peu de blush et gr\u00e2ce \u00e0 mes extensions de cils, je n\u2019ai plus besoin de mascara. La beaut\u00e9 est pour moi naturelle. Idem avec les injections de botox\u00a0: j\u2019aurais peur de ne plus \u00eatre moi-m\u00eame. Je me prot\u00e8ge toujours du soleil, cela pr\u00e9serve ma peau du vieillissement. \u00bb<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"  aligncenter wp-image-9187\" src=\"http:\/\/www.life-magazine.be\/fr\/wp-content\/uploads\/2015\/12\/Melanie.jpg\" alt=\"life-magazine\" width=\"256\" height=\"297\" \/><\/p>\n<h1 style=\"text-align: justify;\"><span style=\"color: #ff6600;\">\u00ab\u00a0La vraie beaut\u00e9 vient du ventre \u00bb<\/span><\/h1>\n<p style=\"text-align: justify;\"><strong>\u00a0Pascale Naessens, 45 ans<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0La beaut\u00e9 n\u2019est pas objective, elle est un rayonnement, un sentiment qui vient de l\u2019int\u00e9rieur, elle est le r\u00e9sultat de la connexion entre notre cerveau et notre ventre. C\u2019est une force. On vit trop dans notre t\u00eate, pas assez dans notre ventre, o\u00f9 naissent la passion, la cr\u00e9ativit\u00e9, l\u2019intuition&#8230; On oublie trop souvent l\u2019importance de la nourriture pour notre peau, notre bien-\u00eatre, notre mental, notre sant\u00e9. Je me nourris naturellement et je fais des choix dans ma vie\u00a0: je ne reste pas dans des situations de malaise, je coupe les relations toxiques, j\u2019ose changer de cap, j\u2019ai le courage de m\u2019affirmer, de m\u2019imposer. Quand on vit une existence qu\u2019on a choisie, qui nous correspond, quand on est authentique, on est rayonnante. C\u2019est \u00e7a la vraie beaut\u00e9. Cela ne m\u2019emp\u00eache pas d\u2019\u00eatre tr\u00e8s f\u00e9minine, d\u2019adorer m\u2019amuser avec du maquillage. J\u2019aime utiliser pour ma peau des produits naturels qu\u2019on peut aussi manger\u00a0: huiles de coco, d\u2019amande, d\u2019olive&#8230;\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9189 size-full\" src=\"http:\/\/www.life-magazine.be\/fr\/wp-content\/uploads\/2015\/12\/Pascale.jpg\" alt=\"life-magazine\" width=\"280\" height=\"260\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0<em>*Pascale Naessens est l\u2019auteure de: \u00ab\u00a0Ma cuisine 100\u00a0% nature &#8211; Aliments et recettes qui nous font du bien\u00a0\u00bb, chez Solar \u00c9ditions.<\/em><\/p>\n<h1 style=\"text-align: justify;\"><span style=\"color: #ff6600;\">\u00ab\u00a0\u00catre belle, c\u2019est \u00eatre raccord avec moi-m\u00eame \u00bb<\/span><\/h1>\n<p style=\"text-align: justify;\"><strong>Marie-Martine Israel, 69 ans<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Pour moi, \u00eatre belle, c\u2019est me sentir juste et raccord avec ma vie et avec moi-m\u00eame. Le plus difficile aujourd\u2019hui, c\u2019est de garder son propre fil conducteur au milieu des nombreuses sollicitations. Plus j\u2019avance et plus je vis l\u2019instant pr\u00e9sent, comme en Asie o\u00f9 j\u2019ai beaucoup s\u00e9journ\u00e9. Il faut accepter sa vie et en \u00eatre contente, sans envier les autres. Le tissage relationnel est tr\u00e8s important \u00e0 mes yeux\u00a0: je reste ouverte aux rencontres. Gr\u00e2ce \u00e0 mon ancien m\u00e9tier de styliste, j\u2019aide des jeunes qui cultivent l\u2019indigo et teignent des v\u00eatements de cette couleur en Am\u00e9rique centrale. J\u2019essaye de manger sain et \u00e9quilibr\u00e9. Je prends tr\u00e8s peu de m\u00e9dicaments. Je nage, l\u2019eau me ressource. Je mets un peu de mascara et, quand je sors, un beau rouge \u00e0 l\u00e8vres. Je n\u2019ai pas fait de chirurgie et je n\u2019ai pas envie d\u2019en faire. Je porte les cheveux gris parce que je trouve cela beau et juste. J\u2019utilise beaucoup d\u2019huile de coco, pour mon \u00e9piderme et pour cuisiner. Je suis fid\u00e8le \u00e0 quelques bons cosm\u00e9tiques naturels que j\u2019ach\u00e8te dans un endroit ouvert par un ami, ancien pharmacien\u00a0: Okinaha (<a href=\"http:\/\/www.okinaha.com\" target=\"_blank\">www.okinaha.com<\/a>).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9191 size-full\" src=\"http:\/\/www.life-magazine.be\/fr\/wp-content\/uploads\/2015\/12\/Marie-Martine.jpg\" alt=\"life-magazine\" width=\"280\" height=\"279\" \/><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Life Magazine donne la parole aux femmes. Ravissantes de l\u2019int\u00e9rieur comme de l\u2019ext\u00e9rieur, elles nous signifient leur propre d\u00e9finition de la beaut\u00e9. <\/p>\n","protected":false},"author":2,"featured_media":9198,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[1112],"tags":[380],"class_list":["post-8506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beaute","tag-beaute"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La beaut\u00e9 en pharmacie : t\u00e9moignages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La beaut\u00e9 en pharmacie : t\u00e9moignages\" \/>\n<meta property=\"og:description\" content=\"Reading Time:  3 minutesLife Magazine donne la parole aux femmes. Ravissantes de l\u2019int\u00e9rieur comme de l\u2019ext\u00e9rieur, elles nous signifient leur propre d\u00e9finition de la beaut\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles\" \/>\n<meta property=\"og:site_name\" content=\"Fifty &amp; Me MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-27T06:40:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-07T14:13:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/12\/UNE-belles-belles-belles-Life-Magazine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ga\u00eblle Mauroit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ga\u00eblle Mauroit\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles\",\"name\":\"La beaut\u00e9 en pharmacie : t\u00e9moignages\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/12\/UNE-belles-belles-belles-Life-Magazine.jpg\",\"datePublished\":\"2016-01-27T06:40:42+00:00\",\"dateModified\":\"2018-03-07T14:13:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#primaryimage\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/12\/UNE-belles-belles-belles-Life-Magazine.jpg\",\"contentUrl\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/12\/UNE-belles-belles-belles-Life-Magazine.jpg\",\"width\":600,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Beaut\u00e9\",\"item\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Belles, belles, belles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#website\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/\",\"name\":\"Fifty &amp; Me MAGAZINE\",\"description\":\"Et si la vie commen\u00e7ait \u00e0 50 ans ?\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b\",\"name\":\"Ga\u00eblle Mauroit\",\"url\":\"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/gaelle\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La beaut\u00e9 en pharmacie : t\u00e9moignages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles","og_locale":"fr_FR","og_type":"article","og_title":"La beaut\u00e9 en pharmacie : t\u00e9moignages","og_description":"Reading Time:  3 minutesLife Magazine donne la parole aux femmes. Ravissantes de l\u2019int\u00e9rieur comme de l\u2019ext\u00e9rieur, elles nous signifient leur propre d\u00e9finition de la beaut\u00e9.","og_url":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles","og_site_name":"Fifty &amp; Me MAGAZINE","article_published_time":"2016-01-27T06:40:42+00:00","article_modified_time":"2018-03-07T14:13:30+00:00","og_image":[{"width":600,"height":520,"url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/12\/UNE-belles-belles-belles-Life-Magazine.jpg","type":"image\/jpeg"}],"author":"Ga\u00eblle Mauroit","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ga\u00eblle Mauroit","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles","name":"La beaut\u00e9 en pharmacie : t\u00e9moignages","isPartOf":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#primaryimage"},"image":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#primaryimage"},"thumbnailUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/12\/UNE-belles-belles-belles-Life-Magazine.jpg","datePublished":"2016-01-27T06:40:42+00:00","dateModified":"2018-03-07T14:13:30+00:00","author":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b"},"breadcrumb":{"@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#primaryimage","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/12\/UNE-belles-belles-belles-Life-Magazine.jpg","contentUrl":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-content\/uploads\/2015\/12\/UNE-belles-belles-belles-Life-Magazine.jpg","width":600,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute\/belles-belles-belles#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beaut\u00e9","item":"https:\/\/www.fiftyandmemagazine.be\/fr\/beaute"},{"@type":"ListItem","position":2,"name":"Belles, belles, belles"}]},{"@type":"WebSite","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#website","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/","name":"Fifty &amp; Me MAGAZINE","description":"Et si la vie commen\u00e7ait \u00e0 50 ans ?","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiftyandmemagazine.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fiftyandmemagazine.be\/fr\/#\/schema\/person\/d73538edb012161ebf7d953b667bb15b","name":"Ga\u00eblle Mauroit","url":"https:\/\/www.fiftyandmemagazine.be\/fr\/author\/gaelle"}]}},"modified_by":"Laurie Deboelpaep","_links":{"self":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/8506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/comments?post=8506"}],"version-history":[{"count":0,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/posts\/8506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media\/9198"}],"wp:attachment":[{"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/media?parent=8506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/categories?post=8506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiftyandmemagazine.be\/fr\/wp-json\/wp\/v2\/tags?post=8506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}